{"id":679,"date":"2019-09-09T14:22:48","date_gmt":"2019-09-09T08:52:48","guid":{"rendered":"https:\/\/www.finsafe.in\/financial-wellness\/?page_id=679"},"modified":"2023-12-07T15:45:03","modified_gmt":"2023-12-07T10:15:03","slug":"pension-plans-videos","status":"publish","type":"page","link":"https:\/\/www.finsafe.in\/financial-wellness\/pension-plans-videos\/","title":{"rendered":"Pension Schemes (PPF, EPF, VPF &#038; NPS) &#8211; Videos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"679\" class=\"elementor elementor-679\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87f119d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87f119d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b190ce\" data-id=\"2b190ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d16c0c8 elementor-widget elementor-widget-heading\" data-id=\"d16c0c8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EPF, VPF<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc28855 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc28855\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0af2893\" data-id=\"0af2893\" data-element_type=\"column\" id=\"headings-faq\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48005dc elementor-widget elementor-widget-heading\" data-id=\"48005dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Articles\u200b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d61efd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d61efd5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2a87796\" data-id=\"2a87796\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c55e63 elementor-widget elementor-widget-image\" data-id=\"3c55e63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.business-standard.com\/finance\/personal-finance\/how-to-activate-a-dormant-ppf-account-here-are-the-steps-to-follow-123091500588_1.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/How-to-activate-a-dormant-PPF-account.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/How-to-activate-a-dormant-PPF-account.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/How-to-activate-a-dormant-PPF-account-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/How-to-activate-a-dormant-PPF-account-150x150.jpg 150w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40b6a0d elementor-widget elementor-widget-image\" data-id=\"40b6a0d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/explained-family-pension-under-epfos-employees-pension-scheme-eps-11320531.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/Family-pension-under-EPFOs.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/Family-pension-under-EPFOs.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/Family-pension-under-EPFOs-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/Family-pension-under-EPFOs-150x150.jpg 150w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ddd5ea elementor-widget elementor-widget-image\" data-id=\"6ddd5ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/nps-which-is-the-best-annuity-option-11205461.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/NPS-Which-is-the-best-annuity-option.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/NPS-Which-is-the-best-annuity-option.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/NPS-Which-is-the-best-annuity-option-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/NPS-Which-is-the-best-annuity-option-150x150.jpg 150w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7bc79c elementor-widget elementor-widget-image\" data-id=\"b7bc79c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finhttps:\/\/www.thehindubusinessline.com\/portfolio\/personal-finance\/opting-for-higher-eps-payouts-pros-cons\/article66924013.eceancialexpress.com\/money\/national-pension-system-choosing-right-annuity-schemes\/3090270\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"519\" height=\"338\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/06\/deadline-for-otp-for-higher.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/06\/deadline-for-otp-for-higher.png 519w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/06\/deadline-for-otp-for-higher-300x195.png 300w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa36c4 elementor-widget elementor-widget-image\" data-id=\"3aa36c4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/how-should-you-manage-your-nps-tier-1-account-under-the-new-tax-regime-11680788700878.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/05\/pension305.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/05\/pension305.png 340w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/05\/pension305-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/05\/pension305-150x150.png 150w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f18ca elementor-widget elementor-widget-image\" data-id=\"27f18ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/economictimes.indiatimes.com\/wealth\/save\/how-to-open-an-nps-account-online-using-digilocker-a-step-by-step-guide\/open-an-nps-account-using-digilocker\/slideshow\/95273281.cms\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/04\/image3.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/04\/image3.png 340w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/04\/image3-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/04\/image3-150x150.png 150w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95bbea3 elementor-widget elementor-widget-image\" data-id=\"95bbea3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.financialexpress.com\/money\/who-will-get-money-if-someone-changes-nps-nomination-using-login-credentials-of-a-deceased-subscriber\/2731688\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/who-will-get-money-if-someone-changes-nps-nomination-using-login-credentials-of-a-deceased.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/who-will-get-money-if-someone-changes-nps-nomination-using-login-credentials-of-a-deceased.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/who-will-get-money-if-someone-changes-nps-nomination-using-login-credentials-of-a-deceased-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/who-will-get-money-if-someone-changes-nps-nomination-using-login-credentials-of-a-deceased-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80f16bc elementor-widget elementor-widget-image\" data-id=\"80f16bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/economictimes.indiatimes.com\/wealth\/invest\/nps-investors-can-now-invest-up-to-75-in-equity-till-age-of-60\/articleshow\/95011643.cms\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/nps-investors-can-now-invest-up-to-75-in-equity-till-age-of-60.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/nps-investors-can-now-invest-up-to-75-in-equity-till-age-of-60.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/nps-investors-can-now-invest-up-to-75-in-equity-till-age-of-60-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/11\/nps-investors-can-now-invest-up-to-75-in-equity-till-age-of-60-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbccc04 elementor-widget elementor-widget-image\" data-id=\"bbccc04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/coming-soon-nps-to-allow-subscribers-to-change-asset-allocation-four-times-a-year-8686381.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"552\" height=\"387\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/coming-soon-nps-to-allow-subscribers-to-change-asset-allocation-four-times-a-year.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/coming-soon-nps-to-allow-subscribers-to-change-asset-allocation-four-times-a-year.jpg 552w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/coming-soon-nps-to-allow-subscribers-to-change-asset-allocation-four-times-a-year-300x210.jpg 300w\" sizes=\"(max-width: 552px) 100vw, 552px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd54bf elementor-widget elementor-widget-image\" data-id=\"3dd54bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/explained-how-epfs-taxable-and-non-taxable-accounts-will-work-8645341.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/explained-how-epfs-taxable-and-non-taxable-accounts-will-work.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/explained-how-epfs-taxable-and-non-taxable-accounts-will-work.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/explained-how-epfs-taxable-and-non-taxable-accounts-will-work-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/explained-how-epfs-taxable-and-non-taxable-accounts-will-work-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62b40cc elementor-widget elementor-widget-image\" data-id=\"62b40cc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/what-to-do-when-your-ppf-completes-15-years-8478591.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/what-to-do-when-your-ppf-completes-15-years.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/what-to-do-when-your-ppf-completes-15-years.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/what-to-do-when-your-ppf-completes-15-years-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/what-to-do-when-your-ppf-completes-15-years-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-828f4f9 elementor-widget elementor-widget-image\" data-id=\"828f4f9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.financialexpress.com\/money\/all-you-need-to-know-before-opening-national-pension-system-tier-2-account\/2386186\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/All-you-need-to-know-before-opening-National-Pension-System-Tier-2-Account.jpg\" class=\"attachment-large size-large\" alt=\"All you need to know before opening National Pension System Tier 2 Account\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/All-you-need-to-know-before-opening-National-Pension-System-Tier-2-Account.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/All-you-need-to-know-before-opening-National-Pension-System-Tier-2-Account-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/All-you-need-to-know-before-opening-National-Pension-System-Tier-2-Account-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c47c738 elementor-widget elementor-widget-image\" data-id=\"c47c738\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/economictimes.indiatimes.com\/wealth\/invest\/how-to-merge-multiple-ppf-accounts\/articleshow\/87130967.cms\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/How-to-merge-multiple-PPF-accounts.jpg\" class=\"attachment-large size-large\" alt=\"How to merge multiple PPF accounts\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/How-to-merge-multiple-PPF-accounts.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/How-to-merge-multiple-PPF-accounts-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/How-to-merge-multiple-PPF-accounts-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d98dd79 elementor-widget elementor-widget-image\" data-id=\"d98dd79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.thehindubusinessline.com\/portfolio\/personal-finance\/things-to-remember-when-you-dip-into-pf-money\/article36792577.ece\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Things-to-remember-when-you-dip-into-PF-money.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Things-to-remember-when-you-dip-into-PF-money.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Things-to-remember-when-you-dip-into-PF-money-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Things-to-remember-when-you-dip-into-PF-money-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7625b9b elementor-widget elementor-widget-image\" data-id=\"7625b9b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.thehindubusinessline.com\/portfolio\/personal-finance\/should-those-above-65-years-go-for-the-national-pension-system\/article36291126.ece\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Should-those-above-65-go-for-the-National-Pension-System.jpg\" class=\"attachment-large size-large\" alt=\"Should those above 65 go for the National Pension System\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Should-those-above-65-go-for-the-National-Pension-System.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Should-those-above-65-go-for-the-National-Pension-System-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df96063 elementor-widget elementor-widget-image\" data-id=\"df96063\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/10\/Aadhaar-not-linked-to-EPF-account.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/09\/Aadhaar-not-linked.png\" class=\"attachment-large size-large\" alt=\"Aadhaar not linked to EPF account? Your provident fund deposits will not get credited\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/09\/Aadhaar-not-linked.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/09\/Aadhaar-not-linked-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/09\/Aadhaar-not-linked-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d638bb elementor-widget elementor-widget-image\" data-id=\"4d638bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.thehindubusinessline.com\/portfolio\/personal-finance\/what-you-should-know-about-covid-death-claims-under-esi-and-edli-schemes\/article34699176.ece\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/07\/Covid-death-claim-article.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/07\/Covid-death-claim-article.jpg 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/07\/Covid-death-claim-article-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/07\/Covid-death-claim-article-300x300.jpg 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a8398 elementor-widget elementor-widget-image\" data-id=\"f3a8398\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-interest-for-2019.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-3.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-3.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-3-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-3-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-11bd8cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bd8cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8c3bf56\" data-id=\"8c3bf56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f42ed8 elementor-widget elementor-widget-image\" data-id=\"5f42ed8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/ask-mint-money\/no-interest-will-accrue-on-your-pf-corpus-when-account-becomes-inoperative-11608480731310.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-4.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-4.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-4-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/01\/image-4-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81b663f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81b663f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3c56c6b\" data-id=\"3c56c6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-468327f elementor-widget elementor-widget-image\" data-id=\"468327f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/how-to-read-your-nps-statement-5965821.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-12.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-12.png 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-12-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-12-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-12-360x360.png 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-596103e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"596103e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f9e8d04\" data-id=\"f9e8d04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99a6c57 elementor-widget elementor-widget-image\" data-id=\"99a6c57\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.thehindubusinessline.com\/portfolio\/big-story\/a-beginners-guide-to-investing-in-nps\/article32649876.ece\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-22.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-22.png 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-22-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-22-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-22-360x360.png 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-810d406 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"810d406\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-db975a6\" data-id=\"db975a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e1d6ff elementor-widget elementor-widget-image\" data-id=\"2e1d6ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/ask-mint-money\/pf-account-becomes-inoperative-if-an-employee-retires-after-55-years-of-age-11598198939479.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-313.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-313.png 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-313-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-313-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/11\/pension-313-360x360.png 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5eab0d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5eab0d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7594f43\" data-id=\"7594f43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cdcfc2 elementor-widget elementor-widget-image\" data-id=\"7cdcfc2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/Public-Provident-Fund-rules-for-partial-withdrawal.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/1p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/1p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/1p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/1p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13637be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13637be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-27ab89f\" data-id=\"27ab89f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2637882 elementor-widget elementor-widget-image\" data-id=\"2637882\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/employee-provident-fund-epf-four-ways-to-check-your-account-balance-11596086820453.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/2p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/2p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/2p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/2p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34412f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34412f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ce46136\" data-id=\"ce46136\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ada99a elementor-widget elementor-widget-image\" data-id=\"2ada99a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/a-pf-account-can-become-inoperative-in-the-event-of-no-fresh-contribution-11593101343884.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/3p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/3p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/3p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/3p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9dfcab1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9dfcab1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-166f5ae\" data-id=\"166f5ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9f238a elementor-widget elementor-widget-image\" data-id=\"d9f238a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/How-to-find-out-your-universal-account-number-UAN-and-activate-it-by-EPFO-member-portal-login.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/4p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/4p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/4p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/4p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-60c1d87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60c1d87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7a747b3\" data-id=\"7a747b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e898cbe elementor-widget elementor-widget-image\" data-id=\"e898cbe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/how-salary-cut-impacts-your-pf-corpus-and-gratuity-11592371849768.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/5p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/5p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/5p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/5p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b90f917 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b90f917\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-85193ae\" data-id=\"85193ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0d0dc elementor-widget elementor-widget-image\" data-id=\"db0d0dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Withdrawal-of-PF-with-less-than-5-years-of-contribution-Know-when-it-may-be-tax-free.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/6p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/6p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/6p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/6p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-01640bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01640bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f5c6c11\" data-id=\"f5c6c11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-499cb17 elementor-widget elementor-widget-image\" data-id=\"499cb17\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/interest-earned-from-pf-after-leaving-a-job-is-taxable-in-the-hands-of-employee-11590991826133.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/7p.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/7p.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/7p-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/7p-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d2b157 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d2b157\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a33bf3\" data-id=\"4a33bf3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5fff9c elementor-widget elementor-widget-image\" data-id=\"a5fff9c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/How-to-update-KYC-in-your-EPF-account-2.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-11.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-11.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-11-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-11-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e48cf67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e48cf67\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-22c9981\" data-id=\"22c9981\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cb1c00 elementor-widget elementor-widget-image\" data-id=\"4cb1c00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/5-reasons-for-rejection-of-EPF-withdrawal-claim-and-how-to-avoid-it.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-21.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-21.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-21-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-21-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d930ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d930ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7faf01c\" data-id=\"7faf01c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a86f9a7 elementor-widget elementor-widget-image\" data-id=\"a86f9a7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/you-can-get-a-loan-on-ppf-balance-at-1-should-you-go-for-it-11587560044906.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-3.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-3.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-3-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-3-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a6054b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6054b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-881e48b\" data-id=\"881e48b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7af3434 elementor-widget elementor-widget-image\" data-id=\"7af3434\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.financialexpress.com\/money\/national-pension-system-nps-account-opening-rules-process-documents-photo-sign-opgm-july-1\/1935327\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-4.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-4.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-4-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-4-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-614f3c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"614f3c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-721efd4\" data-id=\"721efd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282a0fe elementor-widget elementor-widget-image\" data-id=\"282a0fe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/how-to-calculate-interest-on-your-epf-balance-11587284304926.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-5-1.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-5-1.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-5-1-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-5-1-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82f6e0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82f6e0c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d052415\" data-id=\"d052415\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec13f0 elementor-widget elementor-widget-image\" data-id=\"6ec13f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/NPS-partial-withdrawal-rules-explained-in-5-points.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-6-1.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-6-1.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-6-1-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-6-1-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a008414 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a008414\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0e9d24e\" data-id=\"0e9d24e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e0011b elementor-widget elementor-widget-image\" data-id=\"0e0011b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/How-to-deposit-money-online-in-your-Post-Office-PPF-account.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"309\" height=\"309\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-7.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-7.png 309w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-7-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/06\/pension-7-300x300.png 300w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5e04f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5e04f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d274036\" data-id=\"d274036\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82d539c elementor-widget elementor-widget-image\" data-id=\"82d539c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/19.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/19.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/19-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/19-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/19-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2720367 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2720367\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cf4c24e\" data-id=\"cf4c24e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d7d21f elementor-widget elementor-widget-image\" data-id=\"1d7d21f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/what-happens-when-you-don-t-claim-epf-11584548492609.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/20.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/20.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/20-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/20-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/20-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f570c93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f570c93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e50511\" data-id=\"4e50511\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a2d197 elementor-widget elementor-widget-image\" data-id=\"6a2d197\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/pf-account-when-and-how-much-you-can-withdraw-after-being-jobless-11583751402848.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/21-1.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/21-1.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/21-1-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/21-1-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/21-1-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c53f89a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c53f89a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5628f2f\" data-id=\"5628f2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5c70ca elementor-widget elementor-widget-image\" data-id=\"e5c70ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.financialexpress.com\/money\/bad-news-employers-contributions-to-epf-nps-would-no-longer-be-entirely-tax-free\/1887854\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/221.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/221.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/221-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/221-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/221-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98c35ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98c35ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-975400b\" data-id=\"975400b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-017e1a7 elementor-widget elementor-widget-image\" data-id=\"017e1a7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/231.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/231.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/231-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/231-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/231-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-63283a3\" data-id=\"63283a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ffcef3 elementor-widget elementor-widget-heading\" data-id=\"0ffcef3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Videos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4a20dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4a20dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-20bcce9\" data-id=\"20bcce9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a0c8e3 elementor-widget elementor-widget-image\" data-id=\"4a0c8e3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=MJ9AAiCLQuc\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/MJ9AAiCLQuc-HQ.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/MJ9AAiCLQuc-HQ.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/MJ9AAiCLQuc-HQ-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeeb6b3 elementor-widget elementor-widget-image\" data-id=\"aeeb6b3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=8v9PEJhV_vE\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/8v9PEJhV_vE-HQ.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/8v9PEJhV_vE-HQ.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/8v9PEJhV_vE-HQ-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d9e51e elementor-widget elementor-widget-image\" data-id=\"8d9e51e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=S3LYA95XwQs\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/S3LYA95XwQs-HQ.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/S3LYA95XwQs-HQ.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/07\/S3LYA95XwQs-HQ-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4277a62 elementor-widget elementor-widget-image\" data-id=\"4277a62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=QjOT3b0ZmDQ\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/10\/EPF-Taxation-Working.jpg\" class=\"attachment-large size-large\" alt=\"EPF Taxation Working\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/10\/EPF-Taxation-Working.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/10\/EPF-Taxation-Working-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1929b86 elementor-widget elementor-widget-image\" data-id=\"1929b86\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=J7N8RWaDfTU\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1-1024x576.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1-300x169.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1-768x432.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1-720x405.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/06\/pen1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e9e66e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e9e66e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5285dde\" data-id=\"5285dde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f80d464 elementor-widget elementor-widget-image\" data-id=\"f80d464\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=s0aHIEfuBK8\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3-1024x576.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3-300x169.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3-768x432.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3-720x405.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/08\/maxresdefault-3.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e7d408 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e7d408\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4c0a4b3\" data-id=\"4c0a4b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-063b186 elementor-widget elementor-widget-image\" data-id=\"063b186\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=6POOq5mqnW0&#038;t=2s\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8-1024x576.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8-1024x576.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8-300x169.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8-768x432.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8-720x405.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/sa8.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a9052b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9052b8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a5d20a\" data-id=\"4a5d20a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dc9081 elementor-widget elementor-widget-image\" data-id=\"8dc9081\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=Ni2F3ZGeOUg\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"480\" height=\"360\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/money2.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/money2.jpg 480w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/money2-300x225.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a1a9d11\" data-id=\"a1a9d11\" data-element_type=\"column\" id=\"about-border\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ace7d62 elementor-widget elementor-widget-heading\" data-id=\"ace7d62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Post<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df73d83 elementor-widget elementor-widget-image\" data-id=\"df73d83\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-819x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-819x1024.jpeg 819w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-240x300.jpeg 240w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-768x960.jpeg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-1229x1536.jpeg 1229w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM-720x900.jpeg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-11-24-at-2.22.45-PM.jpeg 1280w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f6d62f elementor-widget elementor-widget-image\" data-id=\"9f6d62f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-819x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-819x1024.jpeg 819w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-240x300.jpeg 240w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-768x960.jpeg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-1229x1536.jpeg 1229w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM-720x900.jpeg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-02-at-4.02.38-PM.jpeg 1280w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a55dea elementor-widget elementor-widget-image\" data-id=\"8a55dea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-819x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-819x1024.jpeg 819w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-240x300.jpeg 240w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-768x961.jpeg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-1228x1536.jpeg 1228w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM-720x901.jpeg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-20-at-1.27.06-PM.jpeg 1279w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-914aad9 elementor-widget elementor-widget-image\" data-id=\"914aad9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-819x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-819x1024.jpeg 819w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-240x300.jpeg 240w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-768x960.jpeg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-1229x1536.jpeg 1229w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM-720x900.jpeg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-21-at-2.27.51-PM.jpeg 1280w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-438f9a1 elementor-widget elementor-widget-image\" data-id=\"438f9a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-1024x1024.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-768x768.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-1536x1536.jpg 1536w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-2048x2048.jpg 2048w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-720x720.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Opting-for-higher-pension-on-actual-salary-01-01-360x360.jpg 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fe3a2a elementor-widget elementor-widget-image\" data-id=\"5fe3a2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"871\" height=\"877\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits.jpg 871w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits-298x300.jpg 298w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits-768x773.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/NPS-Tax-Benefits-720x725.jpg 720w\" sizes=\"(max-width: 871px) 100vw, 871px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d019e4d elementor-widget elementor-widget-image\" data-id=\"d019e4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"869\" height=\"865\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS.jpg 869w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS-768x764.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2023\/08\/Equity-Allocation-in-NPS-720x717.jpg 720w\" sizes=\"(max-width: 869px) 100vw, 869px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb3243 elementor-widget elementor-widget-image\" data-id=\"3eb3243\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-1024x1024.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-768x768.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-720x720.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1-360x360.jpg 360w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/05\/April-week1.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d0e08 elementor-widget elementor-widget-image\" data-id=\"24d0e08\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"843\" height=\"843\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3.png 843w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3-150x150.png 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3-300x300.png 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3-768x768.png 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3-720x720.png 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/March-3-360x360.png 360w\" sizes=\"(max-width: 843px) 100vw, 843px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31f8b4d elementor-widget elementor-widget-image\" data-id=\"31f8b4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"770\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1-300x241.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1-768x616.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/03\/Jan-1-720x578.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d5b72 elementor-widget elementor-widget-image\" data-id=\"50d5b72\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021-724x1024.jpg\" class=\"attachment-large size-large\" alt=\"17-12-2021\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021-724x1024.jpg 724w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021-212x300.jpg 212w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021-768x1086.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021-720x1018.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/17-12-2021.jpg 1448w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1382dda elementor-widget elementor-widget-image\" data-id=\"1382dda\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021-724x1024.png\" class=\"attachment-large size-large\" alt=\"Tip of the week-25th Nov 2021\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021-724x1024.png 724w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021-212x300.png 212w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021-768x1087.png 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021-720x1019.png 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-25th-Nov-2021.png 843w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d31bb9 elementor-widget elementor-widget-image\" data-id=\"2d31bb9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021-724x1024.jpg\" class=\"attachment-large size-large\" alt=\"Tip of the week-11th Nov 2021\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021-724x1024.jpg 724w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021-212x300.jpg 212w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021-768x1087.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021-720x1019.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/Tip-of-the-week-11th-Nov-2021.jpg 843w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc7d25 elementor-widget elementor-widget-image\" data-id=\"4fc7d25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct-724x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct-724x1024.png 724w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct-212x300.png 212w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct-768x1087.png 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct-720x1019.png 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/National-Pension-Scheme-NPS-21st-Oct.png 1447w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b529209 elementor-widget elementor-widget-image\" data-id=\"b529209\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September-724x1024.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September-724x1024.png 724w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September-212x300.png 212w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September-768x1087.png 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September-720x1019.png 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/EPF-Post-9th-September.png 1447w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c368e1 elementor-widget elementor-widget-image\" data-id=\"7c368e1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-8-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-911b839 elementor-widget elementor-widget-image\" data-id=\"911b839\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-07-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a579185 elementor-widget elementor-widget-image\" data-id=\"a579185\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-6-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cea705 elementor-widget elementor-widget-image\" data-id=\"9cea705\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-05-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fe005d elementor-widget elementor-widget-image\" data-id=\"1fe005d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-4.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-04.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-04.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-04-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-04-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-04-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bbe04a elementor-widget elementor-widget-image\" data-id=\"5bbe04a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-3.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-03.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-03.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-03-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-03-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-03-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b39ac3b elementor-widget elementor-widget-image\" data-id=\"b39ac3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-2.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-02.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-02.jpg 960w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-02-300x225.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-02-768x576.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-02-720x540.jpg 720w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0481f8f elementor-widget elementor-widget-image\" data-id=\"0481f8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"711\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1-1024x711.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1-1024x711.jpg 1024w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1-300x208.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1-768x533.jpg 768w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1-720x500.jpg 720w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/POST-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6fcab6f\" data-id=\"6fcab6f\" data-element_type=\"column\" id=\"fixed-side\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3216a73 elementor-widget elementor-widget-heading\" data-id=\"3216a73\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Index<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-016b15e elementor-widget elementor-widget-text-editor\" data-id=\"016b15e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><a href=\"https:\/\/www.finsafe.in\/financial-wellness\/pension-plan-about\/\"><strong>About<\/strong><\/a><\/p><p><a href=\"\/financial-wellness\/\/pension-plans-faqs\/\"><strong>FAQs<\/strong><\/a><\/p><p><a href=\"\/financial-wellness\/pension-plans-videos\/\"><strong>Articles<\/strong><\/a><br \/><a href=\"\/financial-wellness\/pension-plans-videos\/\"><br \/><strong>Videos<\/strong><\/a><\/p><p><a href=\"\/financial-wellness\/pension-schemes-ppf-epf-vpf-nps-calculators-finguide\/\"><strong>Calculators <\/strong><\/a><\/p><p><a href=\"\/financial-wellness\/pension-schemes-ppf-epf-vpf-nps-calculators-finguide\/\"><strong> Finguide<\/strong><\/a><\/p><p><a href=\"#\"><strong> Post<\/strong><\/a><\/p><p><a href=\"\/financial-wellness\/pension-plans-glossary\/\"><strong> Glossary<\/strong><\/a><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f78ee5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f78ee5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02fde53\" data-id=\"02fde53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f40b30 elementor-widget elementor-widget-heading\" data-id=\"4f40b30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PPF<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fb8073 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fb8073\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0c5ae0a\" data-id=\"0c5ae0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18873bb elementor-widget elementor-widget-heading\" data-id=\"18873bb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Articles\u200b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b60bae6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b60bae6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b120554\" data-id=\"b120554\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b67f41 elementor-widget elementor-widget-image\" data-id=\"4b67f41\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/241.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/241.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/241-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/241-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/241-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb0fa32 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb0fa32\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b37e0c1\" data-id=\"b37e0c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43e2f26 elementor-widget elementor-widget-image\" data-id=\"43e2f26\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/PPF-account.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/251.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/251.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/251-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/251-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/251-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a37339a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a37339a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-13efb87\" data-id=\"13efb87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c40b51b elementor-widget elementor-widget-image\" data-id=\"c40b51b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/new-ppf-rules-five-recent-changes-you-should-know-11582277320191.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/261.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/261.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/261-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/261-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/261-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ec69d6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec69d6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-309f00d\" data-id=\"309f00d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1821a4 elementor-widget elementor-widget-image\" data-id=\"b1821a4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/271.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/271.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/271-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/271-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/271-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8d5a3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8d5a3d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f396a62\" data-id=\"f396a62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eabef0c elementor-widget elementor-widget-image\" data-id=\"eabef0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/PPF-account-will-not-be-liable-to-attachment-New-rules.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/281.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/281.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/281-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/281-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/281-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cd0b637 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd0b637\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-46748c4\" data-id=\"46748c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4300fec elementor-widget elementor-widget-image\" data-id=\"4300fec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/more-than-one-ppf-account-not-allowed-what-happens-when-you-open-a-second-one-11576731342451.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/29.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/29.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/29-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/29-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/29-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e6bc64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e6bc64\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8157404\" data-id=\"8157404\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04d7962 elementor-widget elementor-widget-image\" data-id=\"04d7962\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/how-to-deposit-money-online-in-post-office-ppf-account-through-ippb-11580459674870.html\u00a0\u00a0\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/301.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/301.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/301-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/301-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/301-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63d4e05\" data-id=\"63d4e05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-511aabb elementor-widget elementor-widget-heading\" data-id=\"511aabb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Videos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-26edc1d\" data-id=\"26edc1d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-749c1a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"749c1a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3519a57\" data-id=\"3519a57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b94ca8 elementor-widget elementor-widget-heading\" data-id=\"8b94ca8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NPS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb1b09a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb1b09a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a15166e\" data-id=\"a15166e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c1d129 elementor-widget elementor-widget-heading\" data-id=\"4c1d129\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Articles\u200b<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12791b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12791b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0e8c33d\" data-id=\"0e8c33d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56bca94 elementor-widget elementor-widget-image\" data-id=\"56bca94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.livemint.com\/money\/personal-finance\/gratuity-benefits-of-government-employees-under-nps-clarified-5-points-11582550133574.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/43.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/43.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/43-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/43-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/43-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea2927b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea2927b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3903661\" data-id=\"3903661\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-020b9a9 elementor-widget elementor-widget-image\" data-id=\"020b9a9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2021\/11\/Want-to-invest-in-NPS.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/44.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/44.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/44-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/44-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/44-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bdfe2dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdfe2dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fbb6238\" data-id=\"fbb6238\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca9ca2 elementor-widget elementor-widget-image\" data-id=\"5ca9ca2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.moneycontrol.com\/news\/business\/personal-finance\/nps-how-to-choose-between-the-auto-and-active-investment-options-4865901.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/45.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/45.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/45-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/45-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/45-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8abc120 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8abc120\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-44c62f1\" data-id=\"44c62f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6fda27 elementor-widget elementor-widget-image\" data-id=\"b6fda27\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2022\/01\/PFRDA-allows-overseas-citizens-to-invest-in-NPS.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"668\" height=\"668\" src=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/46.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/46.jpg 668w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/46-150x150.jpg 150w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/46-300x300.jpg 300w, https:\/\/www.finsafe.in\/financial-wellness\/wp-content\/uploads\/2020\/04\/46-360x360.jpg 360w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ad29474\" data-id=\"ad29474\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ca82ac elementor-widget elementor-widget-heading\" data-id=\"2ca82ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Videos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-37c7b9c\" data-id=\"37c7b9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d18edf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d18edf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-185f49a\" data-id=\"185f49a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-107e88c elementor-widget elementor-widget-text-editor\" data-id=\"107e88c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"font-size: 12px;\"><b>Disclaimer :<\/b> The purpose of the Training Materials and the resources is to encourage you to plan for \u00a0investments based on \u00a0goals and is solely meant for education purposes. There is no guarantee that \u00a0goals will be achieved. The workforce are advised to consult their investment \/ financial advisor, prior to taking any investment decisions. While, every care has been taken in preparing the Training Materials and the Documentation to ensure accuracy at the time of publication and creation, however, FINSAFE India Private Ltd assumes no responsibility for any errors, which despite all precautions may be found herein. Finsafe India Private Limited shall not be liable under, or in connection with:<\/p>\n\n<ul style=\"padding-left: 131px; font-size: 12px;\">\n \t<li>loss of income;<\/li>\n \t<li>loss of business profits or contracts;<\/li>\n \t<li>business interruption;<\/li>\n \t<li>loss of the use of money or anticipated savings<\/li>\n \t<li>loss of information<\/li>\n \t<li>loss of opportunity, goodwill or reputation;<\/li>\n \t<li>loss of, damage to or corruption of data; or\nany indirect or consequential loss or damage of any kind howsoever arising and whether caused<\/li>\n<\/ul>\n<p style=\"font-size: 12px;\">All intellectual property rights in the Training Materials and the resources (whether registered or not) anywhere in the world belong to Finsafe India Private Limited.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EPF, VPF Articles\u200b Videos Post Index About FAQs ArticlesVideos Calculators Finguide Post Glossary PPF Articles\u200b Videos NPS Articles\u200b Videos Disclaimer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/pages\/679"}],"collection":[{"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/comments?post=679"}],"version-history":[{"count":82,"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/pages\/679\/revisions"}],"predecessor-version":[{"id":12377,"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/pages\/679\/revisions\/12377"}],"wp:attachment":[{"href":"https:\/\/www.finsafe.in\/financial-wellness\/wp-json\/wp\/v2\/media?parent=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}